{"id":3437,"count":3,"description":"","link":"https:\/\/ek-mag.com\/el\/tag\/maison-de-campagne-2025-el\/","name":"Maison de Campagne 2025","slug":"maison-de-campagne-2025-el","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Maison de Campagne 2025 Archives | ek magazine | Architectural Publications<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ek-mag.com\/el\/tag\/maison-de-campagne-2025-el\/\" \/>\n<meta property=\"og:locale\" content=\"el_GR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Maison de Campagne 2025 Archives | ek magazine | Architectural Publications\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ek-mag.com\/el\/tag\/maison-de-campagne-2025-el\/\" \/>\n<meta property=\"og:site_name\" content=\"ek magazine | Architectural Publications\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ek-mag.com\/wp-content\/uploads\/2026\/04\/kk.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/ek-mag.com\\\/el\\\/tag\\\/maison-de-campagne-2025-el\\\/\",\"url\":\"https:\\\/\\\/ek-mag.com\\\/el\\\/tag\\\/maison-de-campagne-2025-el\\\/\",\"name\":\"Maison de Campagne 2025 Archives | ek magazine | Architectural Publications\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ek-mag.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ek-mag.com\\\/el\\\/tag\\\/maison-de-campagne-2025-el\\\/#breadcrumb\"},\"inLanguage\":\"el\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ek-mag.com\\\/el\\\/tag\\\/maison-de-campagne-2025-el\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ek-mag.com\\\/el\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Maison de Campagne 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ek-mag.com\\\/#website\",\"url\":\"https:\\\/\\\/ek-mag.com\\\/\",\"name\":\"ek magazine\",\"description\":\"Architecture, Interior Design and Contemporary Design Projects\",\"publisher\":{\"@id\":\"https:\\\/\\\/ek-mag.com\\\/#organization\"},\"alternateName\":\"ek-mag\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ek-mag.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"el\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ek-mag.com\\\/#organization\",\"name\":\"ek magazine | Architectural Publications\",\"alternateName\":\"ek magazine\",\"url\":\"https:\\\/\\\/ek-mag.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"el\",\"@id\":\"https:\\\/\\\/ek-mag.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ek-mag.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/ek_Logo-black.jpg\",\"contentUrl\":\"https:\\\/\\\/ek-mag.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/ek_Logo-black.jpg\",\"width\":1638,\"height\":1504,\"caption\":\"ek magazine | Architectural Publications\"},\"image\":{\"@id\":\"https:\\\/\\\/ek-mag.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ekmagazine\\\/\",\"https:\\\/\\\/www.instagram.com\\\/ek_magazine\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/ek_magazine\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@ekmagazine\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Maison de Campagne 2025 Archives | ek magazine | Architectural Publications","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ek-mag.com\/el\/tag\/maison-de-campagne-2025-el\/","og_locale":"el_GR","og_type":"article","og_title":"Maison de Campagne 2025 Archives | ek magazine | Architectural Publications","og_url":"https:\/\/ek-mag.com\/el\/tag\/maison-de-campagne-2025-el\/","og_site_name":"ek magazine | Architectural Publications","og_image":[{"width":1200,"height":675,"url":"https:\/\/ek-mag.com\/wp-content\/uploads\/2026\/04\/kk.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/ek-mag.com\/el\/tag\/maison-de-campagne-2025-el\/","url":"https:\/\/ek-mag.com\/el\/tag\/maison-de-campagne-2025-el\/","name":"Maison de Campagne 2025 Archives | ek magazine | Architectural Publications","isPartOf":{"@id":"https:\/\/ek-mag.com\/#website"},"breadcrumb":{"@id":"https:\/\/ek-mag.com\/el\/tag\/maison-de-campagne-2025-el\/#breadcrumb"},"inLanguage":"el"},{"@type":"BreadcrumbList","@id":"https:\/\/ek-mag.com\/el\/tag\/maison-de-campagne-2025-el\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ek-mag.com\/el\/"},{"@type":"ListItem","position":2,"name":"Maison de Campagne 2025"}]},{"@type":"WebSite","@id":"https:\/\/ek-mag.com\/#website","url":"https:\/\/ek-mag.com\/","name":"ek magazine","description":"Architecture, Interior Design and Contemporary Design Projects","publisher":{"@id":"https:\/\/ek-mag.com\/#organization"},"alternateName":"ek-mag","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ek-mag.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"el"},{"@type":"Organization","@id":"https:\/\/ek-mag.com\/#organization","name":"ek magazine | Architectural Publications","alternateName":"ek magazine","url":"https:\/\/ek-mag.com\/","logo":{"@type":"ImageObject","inLanguage":"el","@id":"https:\/\/ek-mag.com\/#\/schema\/logo\/image\/","url":"https:\/\/ek-mag.com\/wp-content\/uploads\/2025\/09\/ek_Logo-black.jpg","contentUrl":"https:\/\/ek-mag.com\/wp-content\/uploads\/2025\/09\/ek_Logo-black.jpg","width":1638,"height":1504,"caption":"ek magazine | Architectural Publications"},"image":{"@id":"https:\/\/ek-mag.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ekmagazine\/","https:\/\/www.instagram.com\/ek_magazine\/","https:\/\/www.linkedin.com\/company\/ek_magazine\/","https:\/\/www.youtube.com\/@ekmagazine"]}]}},"_links":{"self":[{"href":"https:\/\/ek-mag.com\/el\/wp-json\/wp\/v2\/tags\/3437","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ek-mag.com\/el\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/ek-mag.com\/el\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/ek-mag.com\/el\/wp-json\/wp\/v2\/posts?tags=3437"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}